{"id":341,"date":"2018-12-26T18:25:56","date_gmt":"2018-12-26T18:25:56","guid":{"rendered":"https:\/\/pepereina25.com\/contacta\/"},"modified":"2019-06-19T16:39:48","modified_gmt":"2019-06-19T16:39:48","slug":"contact-me","status":"publish","type":"page","link":"https:\/\/pepereina25.com\/en\/contact-me\/","title":{"rendered":"Contact me"},"content":{"rendered":"\n\t<section class=\"section contacto-section dark\" id=\"section_1584996466\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1097\" src=\"https:\/\/pepereina25.com\/wp-content\/uploads\/2019\/05\/pepe-reina-sobre-mi-bg.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-collapse row-full-width align-middle\"  id=\"row-1777027886\">\n\n\t<div id=\"col-184614307\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-1019578191\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"672\" height=\"1024\" src=\"https:\/\/pepereina25.com\/wp-content\/uploads\/2019\/05\/pepe-reina-contacto-672x1024.jpg\" class=\"bg attachment-large size-large\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1019578191 {\n  padding-top: 90vh;\n  background-color: rgba(255, 255, 255, 0);\n}\n#banner-1019578191 .banner-bg img {\n  object-position: 37% 24%;\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-155299554\" class=\"col columna-contacto medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"text-center\" style=\"width:500px;max-width:100%;color:#000;margin:0 auto;display:block;letter-spacing:-1px;\">\n<div style=\"padding:30px 0 15px 0;\"><strong style=\"font-size:230%;\">Follow me on:<\/strong>\n<\/div>\n<\/div>\n<div class=\"social-icons follow-icons full-width text-center\" style=\"font-size:130%\"><a href=\"https:\/\/www.facebook.com\/pepereinaofficial\/\" target=\"_blank\" data-label=\"Facebook\" class=\"icon primary button circle facebook tooltip\" title=\"Follow on Facebook\" aria-label=\"Follow on Facebook\" rel=\"noopener nofollow\" ><i class=\"icon-facebook\" ><\/i><\/a><a href=\"https:\/\/www.instagram.com\/preinaofficial\/?hl=es\" target=\"_blank\" data-label=\"Instagram\" class=\"icon primary button circle instagram tooltip\" title=\"Follow on Instagram\" aria-label=\"Follow on Instagram\" rel=\"noopener nofollow\" ><i class=\"icon-instagram\" ><\/i><\/a><a href=\"https:\/\/twitter.com\/preina25?lang=es\" data-label=\"Twitter\" target=\"_blank\" class=\"icon primary button circle twitter tooltip\" title=\"Follow on Twitter\" aria-label=\"Follow on Twitter\" rel=\"noopener nofollow\" ><i class=\"icon-twitter\" ><\/i><\/a><\/div>\n<div class=\"text-center\" style=\"width:500px;max-width:100%;color:#000;margin:0 auto;display:block;letter-spacing:-1px;\">\n<hr style=\"border-color:#000;opacity:0.8;width:100%;\" \/>\n<div style=\"font-size:150%;padding:20px 0;\">\n<strong>Commercial contact<\/strong><\/div>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f402-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"402\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/341#wpcf7-f402-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"402\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.3\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f402-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col medium-6\" style=\"padding-bottom:0;\">\n\t\t<div>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name *\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col medium-6\" style=\"padding-bottom:0;\">\n\t\t<div>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"empresa\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Company *\" value=\"\" type=\"text\" name=\"empresa\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col medium-6\" style=\"padding-bottom:0;\">\n\t\t<div>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email *\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col medium-6\" style=\"padding-bottom:0;\">\n\t\t<div>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone number *\" value=\"\" type=\"text\" name=\"telefono\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Message *\" name=\"your-message\"><\/textarea><\/span>\n\t<\/p>\n<\/div>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1584996466 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  min-height: 85vh;\n}\n#section_1584996466 .section-bg img {\n  object-position: 51% 0%;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-341","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contact me - Pepe Reina - P\u00e1gina web oficial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pepereina25.com\/en\/contact-me\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact me - Pepe Reina - P\u00e1gina web oficial\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pepereina25.com\/en\/contact-me\/\" \/>\n<meta property=\"og:site_name\" content=\"Pepe Reina - P\u00e1gina web oficial\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-19T16:39:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pepereina25.com\/en\/contact-me\/\",\"url\":\"https:\/\/pepereina25.com\/en\/contact-me\/\",\"name\":\"Contact me - Pepe Reina - P\u00e1gina web oficial\",\"isPartOf\":{\"@id\":\"https:\/\/pepereina25.com\/#website\"},\"datePublished\":\"2018-12-26T18:25:56+00:00\",\"dateModified\":\"2019-06-19T16:39:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/pepereina25.com\/en\/contact-me\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pepereina25.com\/en\/contact-me\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pepereina25.com\/en\/contact-me\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/pepereina25.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact me\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pepereina25.com\/#website\",\"url\":\"https:\/\/pepereina25.com\/\",\"name\":\"Pepe Reina - P\u00e1gina web oficial\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pepereina25.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact me - Pepe Reina - P\u00e1gina web oficial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pepereina25.com\/en\/contact-me\/","og_locale":"en_US","og_type":"article","og_title":"Contact me - Pepe Reina - P\u00e1gina web oficial","og_url":"https:\/\/pepereina25.com\/en\/contact-me\/","og_site_name":"Pepe Reina - P\u00e1gina web oficial","article_modified_time":"2019-06-19T16:39:48+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pepereina25.com\/en\/contact-me\/","url":"https:\/\/pepereina25.com\/en\/contact-me\/","name":"Contact me - Pepe Reina - P\u00e1gina web oficial","isPartOf":{"@id":"https:\/\/pepereina25.com\/#website"},"datePublished":"2018-12-26T18:25:56+00:00","dateModified":"2019-06-19T16:39:48+00:00","breadcrumb":{"@id":"https:\/\/pepereina25.com\/en\/contact-me\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pepereina25.com\/en\/contact-me\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pepereina25.com\/en\/contact-me\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pepereina25.com\/en\/"},{"@type":"ListItem","position":2,"name":"Contact me"}]},{"@type":"WebSite","@id":"https:\/\/pepereina25.com\/#website","url":"https:\/\/pepereina25.com\/","name":"Pepe Reina - P\u00e1gina web oficial","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pepereina25.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/pepereina25.com\/en\/wp-json\/wp\/v2\/pages\/341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pepereina25.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pepereina25.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pepereina25.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pepereina25.com\/en\/wp-json\/wp\/v2\/comments?post=341"}],"version-history":[{"count":5,"href":"https:\/\/pepereina25.com\/en\/wp-json\/wp\/v2\/pages\/341\/revisions"}],"predecessor-version":[{"id":435,"href":"https:\/\/pepereina25.com\/en\/wp-json\/wp\/v2\/pages\/341\/revisions\/435"}],"wp:attachment":[{"href":"https:\/\/pepereina25.com\/en\/wp-json\/wp\/v2\/media?parent=341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}